{"id":15933,"date":"2024-09-13T14:13:50","date_gmt":"2024-09-13T21:13:50","guid":{"rendered":"https:\/\/antiquesarmsandarmor.com\/?post_type=envira&#038;p=15933"},"modified":"2024-09-13T14:13:50","modified_gmt":"2024-09-13T21:13:50","slug":"vintage-coca-cola-1941-poster-20x36","status":"publish","type":"envira","link":"https:\/\/antiquesarmsandarmor.com\/index.php\/envira\/vintage-coca-cola-1941-poster-20x36\/","title":{"rendered":"Vintage  Coca Cola 1941 Poster, 20&#215;36\u201d"},"author":1,"featured_media":0,"template":"","class_list":["post-15933","envira","type-envira","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vintage Coca Cola 1941 Poster, 20x36\u201d - Antiques Arms and Armor<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/antiquesarmsandarmor.com\/index.php\/envira\/vintage-coca-cola-1941-poster-20x36\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vintage Coca Cola 1941 Poster, 20x36\u201d - Antiques Arms and Armor\" \/>\n<meta property=\"og:url\" content=\"https:\/\/antiquesarmsandarmor.com\/index.php\/envira\/vintage-coca-cola-1941-poster-20x36\/\" \/>\n<meta property=\"og:site_name\" content=\"Antiques Arms and Armor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/antiquesarmsandarmor.com\\\/index.php\\\/envira\\\/vintage-coca-cola-1941-poster-20x36\\\/\",\"url\":\"https:\\\/\\\/antiquesarmsandarmor.com\\\/index.php\\\/envira\\\/vintage-coca-cola-1941-poster-20x36\\\/\",\"name\":\"Vintage Coca Cola 1941 Poster, 20x36\u201d - Antiques Arms and Armor\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/antiquesarmsandarmor.com\\\/#website\"},\"datePublished\":\"2024-09-13T21:13:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/antiquesarmsandarmor.com\\\/index.php\\\/envira\\\/vintage-coca-cola-1941-poster-20x36\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/antiquesarmsandarmor.com\\\/index.php\\\/envira\\\/vintage-coca-cola-1941-poster-20x36\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/antiquesarmsandarmor.com\\\/index.php\\\/envira\\\/vintage-coca-cola-1941-poster-20x36\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/antiquesarmsandarmor.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vintage Coca Cola 1941 Poster, 20&#215;36\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/antiquesarmsandarmor.com\\\/#website\",\"url\":\"https:\\\/\\\/antiquesarmsandarmor.com\\\/\",\"name\":\"Antiques Arms and Armor\",\"description\":\"Historical Investments\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/antiquesarmsandarmor.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vintage Coca Cola 1941 Poster, 20x36\u201d - Antiques Arms and Armor","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/antiquesarmsandarmor.com\/index.php\/envira\/vintage-coca-cola-1941-poster-20x36\/","og_locale":"en_US","og_type":"article","og_title":"Vintage Coca Cola 1941 Poster, 20x36\u201d - Antiques Arms and Armor","og_url":"https:\/\/antiquesarmsandarmor.com\/index.php\/envira\/vintage-coca-cola-1941-poster-20x36\/","og_site_name":"Antiques Arms and Armor","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/antiquesarmsandarmor.com\/index.php\/envira\/vintage-coca-cola-1941-poster-20x36\/","url":"https:\/\/antiquesarmsandarmor.com\/index.php\/envira\/vintage-coca-cola-1941-poster-20x36\/","name":"Vintage Coca Cola 1941 Poster, 20x36\u201d - Antiques Arms and Armor","isPartOf":{"@id":"https:\/\/antiquesarmsandarmor.com\/#website"},"datePublished":"2024-09-13T21:13:50+00:00","breadcrumb":{"@id":"https:\/\/antiquesarmsandarmor.com\/index.php\/envira\/vintage-coca-cola-1941-poster-20x36\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/antiquesarmsandarmor.com\/index.php\/envira\/vintage-coca-cola-1941-poster-20x36\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/antiquesarmsandarmor.com\/index.php\/envira\/vintage-coca-cola-1941-poster-20x36\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/antiquesarmsandarmor.com\/"},{"@type":"ListItem","position":2,"name":"Vintage Coca Cola 1941 Poster, 20&#215;36\u201d"}]},{"@type":"WebSite","@id":"https:\/\/antiquesarmsandarmor.com\/#website","url":"https:\/\/antiquesarmsandarmor.com\/","name":"Antiques Arms and Armor","description":"Historical Investments","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/antiquesarmsandarmor.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"gallery_data":{"id":15933,"gallery":[{"status":"active","src":"https:\/\/antiquesarmsandarmor.com\/wp-content\/uploads\/2024\/09\/2-25-300x300_c.jpg","title":"2","link":"https:\/\/antiquesarmsandarmor.com\/wp-content\/uploads\/2024\/09\/2-25.jpg","alt":"","caption":"","thumb":"","id":15936,"height":300,"width":300},{"status":"active","src":"https:\/\/antiquesarmsandarmor.com\/wp-content\/uploads\/2024\/09\/1-26-300x300_c.jpg","title":"1","link":"https:\/\/antiquesarmsandarmor.com\/wp-content\/uploads\/2024\/09\/1-26.jpg","alt":"","caption":"","thumb":"","id":15934,"height":300,"width":300}],"config":{"type":"default","layout":"square","columns":"2","gallery_theme":"base","justified_margins":1,"justified_last_row":"nojustify","lazy_loading":1,"lazy_loading_delay":500,"gutter":10,"gutter_mobile":0,"margin":10,"image_size":"default","square_size":300,"crop_width":300,"crop_height":300,"crop":1,"crop_position":"c","show_more_text":"Click for more","additional_copy_0":0,"additional_copy_title":0,"additional_copy_caption":0,"additional_copy_title_caption":0,"additional_copy_0_mobile":0,"additional_copy_title_mobile":0,"additional_copy_caption_mobile":0,"additional_copy_title_caption_mobile":0,"gallery_column_title_caption":"0","gallery_column_title_caption_mobile":"0","additional_copy_automatic_0":0,"additional_copy_automatic_title":0,"additional_copy_automatic_caption":0,"additional_copy_automatic_title_caption":0,"additional_copy_automatic_0_mobile":0,"additional_copy_automatic_title_mobile":0,"additional_copy_automatic_caption_mobile":0,"additional_copy_automatic_title_caption_mobile":0,"gallery_automatic_title_caption":"0","gallery_automatic_title_caption_mobile":"0","justified_row_height":150,"description_position":"0","description":"","random":"0","sort_order":"0","sorting_direction":"ASC","image_sizes_random":[],"isotope":false,"lightbox_enabled":1,"gallery_link_enabled":1,"lightbox_theme":"subtle","lightbox_image_size":"default","title_display":"float","lightbox_title_caption":"0","arrows":1,"arrows_position":"inside","toolbar":1,"toolbar_title":0,"toolbar_position":"top","loop":1,"lightbox_open_close_effect":"fade","effect":"fade","supersize":0,"thumbnails_toggle":0,"thumbnails_hide":0,"image_counter":0,"lightbox_html_caption":0,"thumbnails":1,"thumbnails_width":75,"thumbnails_height":50,"thumbnails_position":"bottom","thumbnails_custom_size":0,"mobile":1,"mobile_width":320,"mobile_height":240,"mobile_lightbox":1,"mobile_gallery_link_enabled":0,"mobile_arrows":1,"mobile_toolbar":1,"mobile_thumbnails":1,"mobile_touchwipe_close":0,"mobile_thumbnails_width":75,"mobile_thumbnails_height":50,"mobile_justified_row_height":80,"keyboard":true,"standalone_template":"","classes":[""],"rtl":0,"slug":"vintage-coca-cola-1941-poster-20x36","zoom":1,"zoom_hover":1,"zoom_position":"upper-left","zoom_type":"lens","zoom_effect":"fade-in","zoom_lens_shape":"round","zoom_lens_cursor":1,"zoom_window_size":"medium","zoom_tint_color":"","zoom_tint_color_opacity":"25","zoom_mousewheel":0,"zoom_size":200,"mobile_zoom":0,"title":"Vintage  Coca Cola 1941 Poster, 20&#215;36\u201d"}},"_links":{"self":[{"href":"https:\/\/antiquesarmsandarmor.com\/index.php\/wp-json\/wp\/v2\/envira-gallery\/15933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/antiquesarmsandarmor.com\/index.php\/wp-json\/wp\/v2\/envira-gallery"}],"about":[{"href":"https:\/\/antiquesarmsandarmor.com\/index.php\/wp-json\/wp\/v2\/types\/envira"}],"author":[{"embeddable":true,"href":"https:\/\/antiquesarmsandarmor.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/antiquesarmsandarmor.com\/index.php\/wp-json\/wp\/v2\/media?parent=15933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}